{"id":10362,"date":"2019-09-27T15:28:05","date_gmt":"2019-09-27T13:28:05","guid":{"rendered":"https:\/\/www.triforce-legend.com\/v6\/?p=10362"},"modified":"2019-10-05T12:44:17","modified_gmt":"2019-10-05T10:44:17","slug":"fans-day-15-feuilles-dautomne","status":"publish","type":"post","link":"https:\/\/www.triforce-legend.com\/v6\/fans-day-15-feuilles-dautomne\/","title":{"rendered":"Fan&#8217;s Day #15 : Feuilles d&#8217;automne"},"content":{"rendered":"<p>Alors que le souffle de l&#8217;automne apporte une fra\u00eecheur bienvenue, les feuilles ne sont pas les seules \u00e0 virevolter. Un \u00e9trange spectacle se dessine sous nos yeux.<\/p>\n<p><em>Un, deux, trois !<\/em><\/p>\n<p>Plein de gr\u00e2ce et tout de rose v\u00eatu, notre magnifique <strong>TheTivador<\/strong> se livre \u00e0 un \u00e9tonnant, ent\u00eatant et odorif\u00e9rant ballet. Parviendra-t-il toutefois \u00e0 rivaliser avec les c\u00e9l\u00e8bres pas de danse de l&#8217;Incarnation de Majora ? Rien n&#8217;est moins s\u00fbr si l&#8217;on se fie \u00e0 l&#8217;hilarit\u00e9 g\u00e9n\u00e9rale.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone aligncenter\" src=\"\/\/www.triforce-legend.com\/site\/fansday\/2019\/ZP_Le_Tutu.png\" width=\"500\" height=\"342\"><\/p>\n<p>&nbsp;<\/p>\n<p><em>Un, deux, trois&#8230; quatre !<\/em><\/p>\n<p>Quatre c&#8217;est le nombre d&#8217;artistes mis \u00e0 l&#8217;honneur cette semaine. Leur pseudonymes commencent \u00e0 vous devenir familier, n&#8217;est-ce pas ? Il y a tout d&#8217;abord, <strong>Amnaysia<\/strong> qui renouvelle pour nous sa d\u00e9claration d&#8217;amour \u00e0 la v\u00e9g\u00e9tation et aux arbres. Les recoins humides des for\u00eats Hyliennes n&#8217;ont plus de secret pour ses crayons.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.triforce-legend.com\/v6\/fans-tl\/fan-arts\/amnaysia\/Art29.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/www.triforce-legend.com\/v6\/fans-tl\/fan-arts\/amnaysia\/Art29.jpg\" alt=\"\" width=\"240\" height=\"160\"><\/a><\/p>\n<p>Notre ch\u00e8re <strong>Carmina<\/strong> entrem\u00eale l&#8217;univers de Zelda avec celui de <strong>La Vengeance d&#8217;un Pass\u00e9<\/strong>, en reprenant un personnage de la licence (Saria) et un OC de <strong>Crottou<\/strong> (Sakaru).<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.triforce-legend.com\/v6\/fans-tl\/fan-arts\/carmina\/Art24.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/www.triforce-legend.com\/v6\/fans-tl\/fan-arts\/carmina\/Art24.jpg\" alt=\"\" width=\"240\" height=\"160\"><\/a><\/p>\n<p>Quant \u00e0 <strong>TheTivador<\/strong> c&#8217;est au style chibi qu&#8217;il s&#8217;essaie depuis quelques temps.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.triforce-legend.com\/v6\/fans-tl\/fan-arts\/thetivador\/Art36.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/www.triforce-legend.com\/v6\/fans-tl\/fan-arts\/thetivador\/Art36.jpg\" alt=\"\" width=\"240\" height=\"160\"><\/a><\/p>\n<p>Enfin, si d\u00e9sert ne rime pas n\u00e9cessairement avec automne, les couleurs chatoyantes de l&#8217;aquarelle de <strong>Zeldapeach<\/strong> nous en offre bien les teintes.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.triforce-legend.com\/v6\/fans-tl\/fan-arts\/zeldapeach\/Art163.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/www.triforce-legend.com\/v6\/fans-tl\/fan-arts\/zeldapeach\/Art163.jpg\" alt=\"\" width=\"240\" height=\"160\"><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Les feuilles ne se limitent pas \u00e0 celles des arbres et de nos dessinateurs. Apr\u00e8s nous avoir \u00e9bloui la vue par tant de jolies \u0153uvres, les amateurs de textes ne seront pas en reste puis que TheTivador a r\u00e9dig\u00e9 un nouveau chapitre d&#8217;Urban Zelda plein de rebondissements !<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt;\"><strong><a href=\"https:\/\/www.triforce-legend.com\/v6\/fans\/fan-fictions\/fan-fictions-de-thetivador\/urban-zelda\/#Chap4\" target=\"_blank\" rel=\"noopener noreferrer\">&#8211; Voir le chapitre 4 de Urban Zelda par TheTivador &#8211;<\/a><\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p>Pour cl\u00f4turer tout ceci, voici la suite de la mini BD de Carmina.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.triforce-legend.com\/v6\/fans-tl\/tl-bds\/carmina\/BD7.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/www.triforce-legend.com\/v6\/fans-tl\/tl-bds\/carmina\/BD7.png\" width=\"307\" height=\"435\"><\/a><\/p>\n<p>Pour savoir ce qui effraie tant nos comparses, rendez-vous la semaine prochaine.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alors que le souffle de l&#8217;automne apporte une fra\u00eecheur bienvenue, les feuilles ne sont pas les seules \u00e0 virevolter. Un \u00e9trange spectacle se dessine sous nos yeux. Un, deux, trois ! Plein de gr\u00e2ce et tout de rose v\u00eatu, notre magnifique TheTivador se livre \u00e0 un \u00e9tonnant, ent\u00eatant et odorif\u00e9rant ballet. Parviendra-t-il toutefois \u00e0 rivaliser [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":9509,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[69,66],"tags":[163],"class_list":["post-10362","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fans-day","category-news","tag-fans-day"],"_links":{"self":[{"href":"https:\/\/www.triforce-legend.com\/v6\/wp-json\/wp\/v2\/posts\/10362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.triforce-legend.com\/v6\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.triforce-legend.com\/v6\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.triforce-legend.com\/v6\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.triforce-legend.com\/v6\/wp-json\/wp\/v2\/comments?post=10362"}],"version-history":[{"count":0,"href":"https:\/\/www.triforce-legend.com\/v6\/wp-json\/wp\/v2\/posts\/10362\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.triforce-legend.com\/v6\/wp-json\/wp\/v2\/media\/9509"}],"wp:attachment":[{"href":"https:\/\/www.triforce-legend.com\/v6\/wp-json\/wp\/v2\/media?parent=10362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.triforce-legend.com\/v6\/wp-json\/wp\/v2\/categories?post=10362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.triforce-legend.com\/v6\/wp-json\/wp\/v2\/tags?post=10362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}